{"id":33626,"date":"2024-06-11T09:00:50","date_gmt":"2024-06-11T07:00:50","guid":{"rendered":"https:\/\/reclaimfinance.org\/site\/?p=33626"},"modified":"2024-06-12T14:57:23","modified_gmt":"2024-06-12T12:57:23","slug":"commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies","status":"publish","type":"post","link":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/","title":{"rendered":"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-bottom:20px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-content-alignment:justify;--awb-text-color:var(--awb-color4);--awb-text-font-family:&quot;Montserrat&quot;;--awb-text-font-style:normal;--awb-text-font-weight:700;\"><p><b>Depuis janvier 2024, une commission s\u00e9natoriale \u00e9tudie la mani\u00e8re dont l\u2019Etat s\u2019assure que TotalEnergies respecte les engagements climatiques de la France. La commission d\u2019enqu\u00eate, qui finalise actuellement son rapport, a men\u00e9 42 auditions pour faire la lumi\u00e8re sur les impacts climatiques de l\u2019entreprise et sur les soutiens dont elle b\u00e9n\u00e9ficie de la part de l\u2019Etat. L\u2019audition de plusieurs acteurs financiers a soulign\u00e9 la reconnaissance par les d\u00e9cideurs politiques du r\u00f4le central de la finance dans les orientations du secteur \u00e9nerg\u00e9tique. Reclaim Finance, sollicit\u00e9 pour partager ses analyses avec les s\u00e9nateurs, appelle l\u2019Etat \u00e0 agir \u00e0 travers tous les leviers \u00e0 sa disposition, et rappelle ses principales propositions concernant le secteur financier.<\/b><\/p>\n<\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-content-alignment:justify;\"><p><span style=\"font-weight: 400;\">Lanc\u00e9e par le groupe \u00e9cologiste au S\u00e9nat et pr\u00e9sid\u00e9e par le s\u00e9nateur (Les R\u00e9publicains) des Hauts-de-Seine Roger Karoutchi, la commission d\u2019enqu\u00eate (1) a auditionn\u00e9 des scientifiques du climat, des acad\u00e9miques, des responsables politiques et institutionnels, des dirigeants d\u2019entreprises &#8211; dont TotalEnergies -, des acteurs financiers &#8211; AXA, BNP Paribas et Cr\u00e9dit Agricole &#8211; et des ONG parmi lesquelles Reclaim Finance.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Prenant acte de l\u2019absence de transition \u00e0 attendre de la part de TotalEnergies (2) et de l\u2019insuffisance des mesures volontaires adopt\u00e9es par le secteur financier face \u00e0 l\u2019urgence \u00e9cologique, Reclaim Finance a soulign\u00e9 les moyens par lesquels le levier financier peut pousser TotalEnergies, et derri\u00e8re elle tout le secteur \u00e9nerg\u00e9tique, \u00e0 s\u2019aligner sur l\u2019Accord de Paris (3).<\/span><\/p>\n<\/div><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color4);--awb-margin-top:15px;--awb-margin-bottom:15px;--awb-font-size:16px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Montserrat&quot;;font-style:normal;font-weight:700;margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.5;\"><b>Agir sur la finance pour toucher TotalEnergies et ses pairs<\/b><\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-3\" style=\"--awb-content-alignment:justify;\"><p><span style=\"font-weight: 400;\">Malgr\u00e9 ses superprofits, TotalEnergies demeure d\u00e9pendant du secteur financier pour op\u00e9rer et d\u00e9velopper ses activit\u00e9s &#8211; comme le d\u00e9montre la derni\u00e8re \u00e9mission obligataire d\u2019un montant de 4,25 milliards de dollars, transaction soutenue par le groupe Banque Populaire Caisse d\u2019Epargne (BPCE) et 6 autres banques \u00e9trang\u00e8res (4).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Le levier financier est d\u2019autant plus strat\u00e9gique que les financements \u00e0 TotalEnergies sont tr\u00e8s concentr\u00e9s, notamment parmi les banques fran\u00e7aises qui ont fourni 40% des 12,5 milliards de dollars \u00e0 l\u2019entreprise entre 2021 et 2023<\/span><span style=\"font-weight: 400;\">.<\/span><span style=\"font-weight: 400;\"> BNP Paribas, Cr\u00e9dit Agricole et Soci\u00e9t\u00e9 G\u00e9n\u00e9rale restent les trois premi\u00e8res banques de l\u2019entreprise, avec 36% des flux financiers accord\u00e9s \u00e0 TotalEnergies sur cette p\u00e9riode (5).\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Les banques et acteurs financiers fran\u00e7ais soutenant aussi les concurrents de TotalEnergies, adopter des mesures sur la finance atteindrait non seulement la major fran\u00e7aise mais plus largement toute l\u2019industrie p\u00e9tro-gazi\u00e8re. L\u2019\u00e9chelle europ\u00e9enne est \u00e9galement pertinente en prolongement et compl\u00e9ment de mesures nationales. De nombreux outils au niveau europ\u00e9en sont accessibles, d\u00e9ployables rapidement, et permettraient de couvrir, \u00e0 travers les seules banques europ\u00e9ennes, 56% des financements \u00e0 TotalEnergies (5).\u00a0<\/span><\/p>\n<\/div><div class=\"fusion-title title fusion-title-2 fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color4);--awb-margin-top:15px;--awb-margin-bottom:15px;--awb-font-size:16px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Montserrat&quot;;font-style:normal;font-weight:700;margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.5;\"><b>R\u00e9guler face \u00e0 l\u2019\u00e9chec de l\u2019autor\u00e9gulation\u00a0<\/b><\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-4\" style=\"--awb-content-alignment:justify;\"><p><span style=\"font-weight: 400;\">Les directeurs g\u00e9n\u00e9raux et plusieurs membres des \u00e9quipes dirigeantes d\u2019AXA, BNP Paribas, et Cr\u00e9dit Agricole ont \u00e9t\u00e9 auditionn\u00e9s. Leurs r\u00e9ponses ont r\u00e9v\u00e9l\u00e9 ce qui semble \u00eatre, pour certains, un rapport tr\u00e8s approximatif avec la v\u00e9rit\u00e9 et une faible compr\u00e9hension des mesures \u00e0 mettre en place pour emp\u00eacher un emballement catastrophique du climat. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Philippe Brassac, directeur g\u00e9n\u00e9ral de Cr\u00e9dit Agricole,  a ainsi annonc\u00e9 que sa banque \u201c<\/span><i><span style=\"font-weight: 400;\">ne concentrait ses financements de projets que sur les \u00e9nergies renouvelables et le bas carbone<\/span><\/i><span style=\"font-weight: 400;\">\u201d. Une d\u00e9claration approximative que la banque a corrig\u00e9 par mail apr\u00e8s avoir \u00e9t\u00e9 interpell\u00e9e par Reclaim Finance. La politique interne de la banque autorise en effet toujours les financements directs \u00e0 de nouveaux projets gaziers tels que les terminaux de gaz naturel liqu\u00e9fi\u00e9 (qui exportent du gaz fossile, y compris du gaz de schiste) ou des gazoducs (6). <\/span><\/p>\n<p><span style=\"font-weight: 400;\">Thomas Buberl, directeur g\u00e9n\u00e9ral d\u2019AXA, a aussi d\u00e9fendu le soutien de son groupe \u00e0 TotalEnergies en d\u00e9fendant la strat\u00e9gie de diversification et de\u201ctransition\u201d de la major. Il s\u2019est positionn\u00e9 en fervent d\u00e9fenseur du gaz fossile dont le groupe AXA continue d\u2019assurer le d\u00e9veloppement. Pourtant, le constat est sans appel : TotalEnergies n\u2019est pas en transition, comme suffit \u00e0 le d\u00e9montrer sa projection d\u2019augmentation de sa production d\u2019hydrocarbures de 2 \u00e0 3% par an jusqu&rsquo;en 2028. Cette croissance fait d\u2019elle la deuxi\u00e8me major occidentale \u00e0 pr\u00e9voir une telle hausse, apr\u00e8s l\u2019italienne Eni, bien loin des projections de baisse de plus de 21% et 18% pour la production de p\u00e9trole et de gaz d\u2019ici 2030 dans le sc\u00e9nario Net Zero Emissions (NZE) de l\u2019Agence internationale de l\u2019\u00e9nergie (AIE) (7).<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Si les r\u00e9centes annonces de BNP Paribas et Cr\u00e9dit Agricole concernant leur non participation aux \u00e9missions obligataires pour le secteur p\u00e9tro-gazier (8) vont dans la bonne direction, nous sommes forc\u00e9s de constater que, trois ans apr\u00e8s la publication du premier NZE par l\u2019AIE, tous les grands acteurs financiers fran\u00e7ais peuvent encore accorder des soutiens \u00e0 l\u2019expansion fossile de TotalEnergies. Autrement dit, l\u2019auto-r\u00e9gulation ne produira pas les effets escompt\u00e9s dans le laps de temps imparti. Les pouvoirs publics doivent donc r\u00e9guler. <\/span><\/p>\n<\/div><div class=\"fusion-title title fusion-title-3 fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color4);--awb-margin-top:15px;--awb-margin-bottom:15px;--awb-font-size:16px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Montserrat&quot;;font-style:normal;font-weight:700;margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.5;\"><b>Contraindre, inciter, faciliter, le triptyque r\u00e9glementaire \u00e0 activer<\/b><\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-5\" style=\"--awb-content-alignment:justify;\"><p><span style=\"font-weight: 400;\">Il ne s\u2019agit pas uniquement d\u2019am\u00e9liorer les obligations de transparence et de reporting. Au contraire, l\u2019information n\u2019ayant jamais fait l\u2019action, les pouvoirs publics doivent adopter des r\u00e9glementations normatives, seules \u00e0 m\u00eame d\u2019impacter durablement les comportements des acteurs financiers.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Au-del\u00e0 des mesures contraignantes &#8211; comme l\u2019encadrement de la redistribution des profits ou l\u2019obligation d\u2019adopter un plan de transition comprenant des crit\u00e8res minimums tels que l\u2019arr\u00eat des soutiens \u00e0 l\u2019expansion fossile (9) &#8211; d\u2019autres mesures permettraient de rendre plus cher le financement d\u2019activit\u00e9s polluantes et plus attractifs les financements aux solutions telles que les \u00e9nergies renouvelables ou la r\u00e9novation thermique des b\u00e2timents.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Parmi les mesures jouant sur le couple incitation \/ dissuasion se trouvent la mise en place de taux diff\u00e9renci\u00e9s par la Banque centrale europ\u00e9enne (10), ou le conditionnement de la d\u00e9fiscalisation des produits d\u2019\u00e9pargne et d\u2019investissement au fl\u00e9chage des capitaux hors des entreprises qui d\u00e9veloppent de nouveaux projets fossiles. Des mesures qui ne n\u00e9cessiteraient pas de d\u00e9pense publique suppl\u00e9mentaire.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Enfin, de nombreuses possibilit\u00e9s existent afin d&rsquo;am\u00e9liorer la transparence des produits financiers, comme la mise en place d&rsquo;un \u00ab \u00e9co-score \u00bb , notant les produits financiers selon leur exposition aux \u00e9nergies fossiles (11). Cet arsenal r\u00e9glementaire permettrait de mieux guider le choix des \u00e9pargnants vers des produits financiers \u00ab soutenables \u00bb<\/span><\/p>\n<\/div><div class=\"fusion-text fusion-text-6\" style=\"--awb-content-alignment:justify;\"><p><b>La Commission d\u2019enqu\u00eate s\u00e9natoriale dispose de nombreuses propositions de r\u00e9glementations contraignantes qui permettraient de pousser les acteurs financiers \u00e0 cesser de soutenir les activit\u00e9s qui menacent le climat et \u00e0 massifier leurs soutiens aux solutions. Aux s\u00e9nateurs de s\u2019en saisir pour qu\u2019elles contribuent \u00e0 imposer une transition rapide aux entreprises p\u00e9tro-gazi\u00e8res et \u00e0 mettre fin \u00e0 la strat\u00e9gie climaticide de TotalEnergies.<\/b><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-column-no-min-height\" style=\"--awb-padding-top:20px;--awb-padding-right:10px;--awb-padding-bottom:20px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-size:cover;--awb-border-color:var(--awb-color1);--awb-border-top:1px;--awb-border-right:1px;--awb-border-bottom:1px;--awb-border-left:1px;--awb-border-style:solid;--awb-border-radius:10px 10px 10px 10px;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-4 fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-bottom:0px;--awb-font-size:16px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Montserrat&quot;;font-style:normal;font-weight:700;margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.5;\">Notes :<\/h3><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-7\"><ol>\n<li><span style=\"font-weight: 400;\"><span style=\"text-decoration: underline;\"><a href=\"https:\/\/www.senat.fr\/travaux-parlementaires\/structures-temporaires\/commissions-denquete\/obligations-climatiques-totalenergies.html\">Commission d\u2019enqu\u00eate<\/a>\u00a0<\/span>sur les moyens mobilis\u00e9s et mobilisables par l\u2019\u00c9tat pour assurer la prise en compte et le respect par le groupe TotalEnergies des obligations climatiques et des orientations de la politique \u00e9trang\u00e8re de la France.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Voir<span style=\"text-decoration: underline;\"> l\u2019<\/span><\/span><a href=\"https:\/\/reclaimfinance.org\/site\/evaluation-de-la-strategie-climatique-des-compagnies-petrolieres-et-gazieres\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\"><span style=\"text-decoration: underline;\">Evaluation des strat\u00e9gies climat des entreprises p\u00e9tro-gazi\u00e8res<\/span><\/span><\/a><span style=\"font-weight: 400;\">.\u00a0<\/span><\/li>\n<li>Voir <span style=\"text-decoration: underline;\">l\u2019<\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/videos.senat.fr\/video.4391924_65cdd03fe8d7d.obligations-de-totalenergies--audition-de-reclaim-finance\" target=\"_blank\" rel=\"noopener\">enregistrement de l\u2019audition de Reclaim Finance<\/a><\/span> et la <span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/2403_Reponse-a-la-Commission-denquete-du-Senat.pdf\" target=\"_blank\" rel=\"noopener\">contribution \u00e9crite<\/a><\/span> adress\u00e9e \u00e0 la Commission d\u2019enqu\u00eate.<\/li>\n<li><span style=\"font-weight: 400;\">\u00a0Le 5 avril 2024, TotalEnergies a lev\u00e9 4,25 milliards US$ avec l\u2019aide des banques BofA Securities, Deutsche Bank Securities, Morgan Stanley, MUFG Securities Americas, Natixis Securities North America, SMBC Nikko Securities America et Standard Chartered Bank. Dans la foul\u00e9e, pr\u00e8s de 60 ONGs appelaient \u00e0 <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/2024\/04\/10\/des-ong-appellent-a-couper-le-principal-levier-de-financement-de-total-energies\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">couper le principal levier de financement de TotalEnergies<\/span><\/a><\/span><span style=\"font-weight: 400;\"><span style=\"text-decoration: underline;\">.<\/span>\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">Les banques peuvent soutenir TotalEnergies \u00e0 travers des pr\u00eats \u2013 \u00e0 ses projets d\u2019\u00e9nergies fossiles ou \u00e0 l\u2019entreprise \u2013 ou en l\u2019aidant \u00e0 \u00e9mettre des obligations ou des actions. Les 15 principales banques qui ont soutenu TotalEnergies entre 2021 et 2023 lui ont fourni 12,5 milliards US$ de financements. Les donn\u00e9es pr\u00e9cises <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/defundtotalenergies.org\/qui-finance-totalenergies\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">sont disponibles ici<\/span><\/a><\/span><span style=\"font-weight: 400;\"><span style=\"text-decoration: underline;\">.<\/span>\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">\u00a0En d\u00e9cembre 2023, Cr\u00e9dit Agricole a <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/2023\/12\/14\/climat-credit-agricole-avance-en-trainant-des-pieds\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">annonc\u00e9 l\u2019arr\u00eat des financements de projets de champs gaziers<\/span><\/a><\/span><span style=\"font-weight: 400;\"><span style=\"text-decoration: underline;\">,<\/span> tout en se laissant la possibilit\u00e9 financer de nouveaux projets d\u2019infrastructures fossiles comme les terminaux de gaz naturel liqu\u00e9fi\u00e9, ainsi que des entreprises comme TotalEnergies qui d\u00e9veloppent de nouveaux champs ou infrastructures p\u00e9troli\u00e8res et gazi\u00e8res.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">\u00a0Voir le briefing <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/2023\/09\/26\/briefing-totalenergies-faut-il-croire-a-sa-diversification\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">TotalEnergies, faut-il croire \u00e0 sa diversification?<\/span><\/a><\/span><\/li>\n<li><span style=\"font-weight: 400;\">A l\u2019occasion de leurs assembl\u00e9es g\u00e9n\u00e9rales annuelles, <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/2024\/05\/31\/bnp-paribas-et-credit-agricole-disent-non-aux-obligations-pour-le-secteur-petro-gazier\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">BNP Paribas et Cr\u00e9dit Agricole ont annonc\u00e9<\/span><\/a><\/span><span style=\"font-weight: 400;\"> ne plus participer aux \u00e9missions d\u2019obligations conventionnelles du secteur p\u00e9tro-gazier. Ce faisant, ce sont deux des 10 plus grosses banques au monde qui prennent enfin acte de l\u2019imp\u00e9ratif scientifique de l\u2019arr\u00eat de l\u2019expansion de la production p\u00e9tro-gazi\u00e8re pour le traduire dans un des modes de financements non fl\u00e9ch\u00e9s les plus importants pour le secteur \u00e9nerg\u00e9tique.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">La qualit\u00e9 des plans de transition climat et leur mise en \u0153uvre d\u00e9pendra de la capacit\u00e9 des pouvoirs publics \u00e0 auditer, contr\u00f4ler et sanctionner en cas de plan insuffisant. Reclaim Finance <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/2024\/01\/30\/plans-de-transition-pour-eviter-le-greenwashing-il-faut-des-regles-solides\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">appelle les r\u00e9gulateurs<\/span><\/a><\/span><span style=\"font-weight: 400;\"> fran\u00e7ais et europ\u00e9ens \u00e0 mettre en place des normes solides de contr\u00f4le des plans de transition.\u00a0<\/span><\/li>\n<li><span style=\"font-weight: 400;\">La Banque Centrale Europ\u00e9enne (BCE) d\u00e9finit les taux d\u2019int\u00e9r\u00eat qui s\u2019appliquent aux banques. Ces taux, dits \u201cdirecteurs\u201d, se r\u00e9percutent ensuite sur les taux des pr\u00eats pratiqu\u00e9s par les banques aupr\u00e8s des entreprises, m\u00e9nages et acteurs publics. La BCE pourrait donc d\u00e9finir un \u201c<\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/2024\/01\/11\/taux-dinteret-vert-vs-brun-comment-faire\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">taux diff\u00e9renci\u00e9<\/span><\/a><\/span><span style=\"font-weight: 400;\">\u201d plus bas pour le financement d\u2019activit\u00e9s \u201cvertes\u201d, en commen\u00e7ant par les \u00e9nergies soutenables et la r\u00e9novation \u00e9nerg\u00e9tique.<\/span><\/li>\n<li><span style=\"font-weight: 400;\">A l\u2019image du \u00ab nutri-score \u00bb des produits alimentaires, la cr\u00e9ation d\u2019un \u00ab \u00e9co-score \u00bb appos\u00e9 sur l\u2019ensemble des produits financiers permettrait aux \u00e9pargnants de r\u00e9aliser imm\u00e9diatement si les fonds dans lesquels ils investissent financent les \u00e9nergies fossiles. Voire les recommandations du rapport \u201c<\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/Rapport-Lassurance-vie-a-lere-de-lurgence-climatique.pdf\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">L\u2019assurance-vie \u00e0 l\u2019\u00e8re de l\u2019urgence Climatique : Convoit\u00e9e pour la transition et toujours investie dans l\u2019expansion fossile<\/span><\/a><\/span><span style=\"font-weight: 400;\"><span style=\"text-decoration: underline;\">\u201d<\/span>.\u00a0<\/span><\/li>\n<\/ol>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-5 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-bottom:0px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;text-transform:uppercase;--fontSize:33;line-height:1.5;\">lire aussi<\/h2><\/div><div class=\"fusion-separator\" style=\"align-self: flex-start;margin-right:auto;margin-top:25px;margin-bottom:35px;width:100%;max-width:100px;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color4);border-color:var(--awb-color4);border-top-width:10px;\"><\/div><\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:15px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -15px !important; margin-right:-15px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-blog-rollover fusion-blog-layout-grid fusion-blog-layout-grid-3 isotope fusion-blog-equal-heights\" data-pages=\"183\" data-grid-col-space=\"30\" style=\"margin: -15px -15px 0;min-height:500px;\"><article id=\"blog-1-post-40051\" class=\"fusion-post-grid post-40051 post type-post status-publish format-standard has-post-thumbnail hentry category-blog acteurs_financiers-banques-fr thematique-energies-fossiles thematique-gaz-fr programme-programme-2-fr\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/07\/Nordea1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Gas expansion\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/07\/06\/les-banques-francaises-au-soutien-deph-a-rebours-de-leurs-engagements\/\" aria-label=\"Les banques fran\u00e7aises au soutien d\u2019EPH, \u00e0 rebours de leurs engagements\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/07\/06\/les-banques-francaises-au-soutien-deph-a-rebours-de-leurs-engagements\/\">Les banques fran\u00e7aises au soutien d\u2019EPH, \u00e0 rebours de leurs engagements<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/lma\/\" title=\"Articles par L\u00e9o Martin\" rel=\"author\">L\u00e9o Martin<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-06T15:58:19+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/blog\/\" rel=\"category tag\">Articles<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-40057\" class=\"fusion-post-grid post-40057 post type-post status-publish format-standard has-post-thumbnail hentry category-blog thematique-energies-fossiles thematique-petrole-et-gaz programme-programme-1-fr\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/07\/Nordea.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/07\/06\/nordea-se-demarque-du-soutien-des-banques-europeennes-a-lexpansion-du-gnl\/\" aria-label=\"Nordea se d\u00e9marque du soutien des banques europ\u00e9ennes \u00e0 l&rsquo;expansion du GNL\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/07\/06\/nordea-se-demarque-du-soutien-des-banques-europeennes-a-lexpansion-du-gnl\/\">Nordea se d\u00e9marque du soutien des banques europ\u00e9ennes \u00e0 l&rsquo;expansion du GNL<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/lma\/\" title=\"Articles par L\u00e9o Martin\" rel=\"author\">L\u00e9o Martin<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-06T16:05:25+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/blog\/\" rel=\"category tag\">Articles<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-40027\" class=\"fusion-post-grid post-40027 post type-post status-publish format-standard has-post-thumbnail hentry category-blog thematique-energies-fossiles\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/06\/fossil-fuel-1-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/06\/26\/politiques-fossiles-que-dit-la-recherche-academique\/\" aria-label=\"Politiques fossiles : que dit la recherche acad\u00e9mique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/06\/26\/politiques-fossiles-que-dit-la-recherche-academique\/\">Politiques fossiles : que dit la recherche acad\u00e9mique<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/aman\/\" title=\"Articles par Aatira\u00ef Manickawasagar\" rel=\"author\">Aatira\u00ef Manickawasagar<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-10T11:28:08+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/blog\/\" rel=\"category tag\">Articles<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":26,"featured_media":33631,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"acteurs_financiers":[],"thematique":[2415],"webinar_type":[],"programme":[],"class_list":["post-33626","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","thematique-energies-fossiles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies - Reclaim Finance<\/title>\n<meta name=\"description\" content=\"Depuis janvier 2024, une commission s\u00e9natoriale \u00e9tudie la mani\u00e8re dont l\u2019Etat s\u2019assure que TotalEnergies respecte les engagements climatiques de la France.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies - Reclaim Finance\" \/>\n<meta property=\"og:description\" content=\"Depuis janvier 2024, une commission s\u00e9natoriale \u00e9tudie la mani\u00e8re dont l\u2019Etat s\u2019assure que TotalEnergies respecte les engagements climatiques de la France.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/\" \/>\n<meta property=\"og:site_name\" content=\"Reclaim Finance\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ReclaimFinanceONG\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-11T07:00:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-12T12:57:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ReclaimFinance\" \/>\n<meta name=\"twitter:site\" content=\"@ReclaimFinance\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00e9o Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"13 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/\"},\"author\":{\"name\":\"L\u00e9o Martin\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1\"},\"headline\":\"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies\",\"datePublished\":\"2024-06-11T07:00:50+00:00\",\"dateModified\":\"2024-06-12T12:57:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/\"},\"wordCount\":3598,\"publisher\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/\",\"url\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/\",\"name\":\"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies - Reclaim Finance\",\"isPartOf\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png\",\"datePublished\":\"2024-06-11T07:00:50+00:00\",\"dateModified\":\"2024-06-12T12:57:23+00:00\",\"description\":\"Depuis janvier 2024, une commission s\u00e9natoriale \u00e9tudie la mani\u00e8re dont l\u2019Etat s\u2019assure que TotalEnergies respecte les engagements climatiques de la France.\",\"breadcrumb\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#primaryimage\",\"url\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png\",\"contentUrl\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png\",\"width\":900,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reclaimfinance.org\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#website\",\"url\":\"https:\/\/reclaimfinance.org\/site\/\",\"name\":\"Reclaim Finance\",\"description\":\"Reprendre le contr\u00f4le de la finance pour le climat et la biodiversit\u00e9\",\"publisher\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reclaimfinance.org\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#organization\",\"name\":\"Reclaim Finance\",\"url\":\"https:\/\/reclaimfinance.org\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png\",\"contentUrl\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png\",\"width\":800,\"height\":800,\"caption\":\"Reclaim Finance\"},\"image\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ReclaimFinanceONG\",\"https:\/\/x.com\/ReclaimFinance\",\"https:\/\/www.instagram.com\/reclaimfinance\/\",\"https:\/\/www.linkedin.com\/company\/reclaim-finance-ong-think-tank\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1\",\"name\":\"L\u00e9o Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cebd89becb7f7185483789d7f51a21cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cebd89becb7f7185483789d7f51a21cb?s=96&d=mm&r=g\",\"caption\":\"L\u00e9o Martin\"},\"url\":\"https:\/\/reclaimfinance.org\/site\/author\/lma\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies - Reclaim Finance","description":"Depuis janvier 2024, une commission s\u00e9natoriale \u00e9tudie la mani\u00e8re dont l\u2019Etat s\u2019assure que TotalEnergies respecte les engagements climatiques de la France.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/","og_locale":"fr_FR","og_type":"article","og_title":"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies - Reclaim Finance","og_description":"Depuis janvier 2024, une commission s\u00e9natoriale \u00e9tudie la mani\u00e8re dont l\u2019Etat s\u2019assure que TotalEnergies respecte les engagements climatiques de la France.","og_url":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/","og_site_name":"Reclaim Finance","article_publisher":"https:\/\/www.facebook.com\/ReclaimFinanceONG","article_published_time":"2024-06-11T07:00:50+00:00","article_modified_time":"2024-06-12T12:57:23+00:00","og_image":[{"width":900,"height":400,"url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png","type":"image\/png"}],"author":"L\u00e9o Martin","twitter_card":"summary_large_image","twitter_creator":"@ReclaimFinance","twitter_site":"@ReclaimFinance","twitter_misc":{"\u00c9crit par":"L\u00e9o Martin","Dur\u00e9e de lecture estim\u00e9e":"13 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#article","isPartOf":{"@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/"},"author":{"name":"L\u00e9o Martin","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1"},"headline":"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies","datePublished":"2024-06-11T07:00:50+00:00","dateModified":"2024-06-12T12:57:23+00:00","mainEntityOfPage":{"@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/"},"wordCount":3598,"publisher":{"@id":"https:\/\/reclaimfinance.org\/site\/#organization"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#primaryimage"},"thumbnailUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png","articleSection":["Articles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/","url":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/","name":"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies - Reclaim Finance","isPartOf":{"@id":"https:\/\/reclaimfinance.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#primaryimage"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#primaryimage"},"thumbnailUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png","datePublished":"2024-06-11T07:00:50+00:00","dateModified":"2024-06-12T12:57:23+00:00","description":"Depuis janvier 2024, une commission s\u00e9natoriale \u00e9tudie la mani\u00e8re dont l\u2019Etat s\u2019assure que TotalEnergies respecte les engagements climatiques de la France.","breadcrumb":{"@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#primaryimage","url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png","contentUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2024\/06\/1.-BANNER-SITEWEB-8.png","width":900,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/reclaimfinance.org\/site\/2024\/06\/11\/commission-denquete-senatoriale-reguler-la-finance-pour-contraindre-totalenergies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reclaimfinance.org\/site\/"},{"@type":"ListItem","position":2,"name":"Commission d\u2019enqu\u00eate s\u00e9natoriale : r\u00e9guler la finance pour contraindre TotalEnergies"}]},{"@type":"WebSite","@id":"https:\/\/reclaimfinance.org\/site\/#website","url":"https:\/\/reclaimfinance.org\/site\/","name":"Reclaim Finance","description":"Reprendre le contr\u00f4le de la finance pour le climat et la biodiversit\u00e9","publisher":{"@id":"https:\/\/reclaimfinance.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reclaimfinance.org\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/reclaimfinance.org\/site\/#organization","name":"Reclaim Finance","url":"https:\/\/reclaimfinance.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png","contentUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png","width":800,"height":800,"caption":"Reclaim Finance"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ReclaimFinanceONG","https:\/\/x.com\/ReclaimFinance","https:\/\/www.instagram.com\/reclaimfinance\/","https:\/\/www.linkedin.com\/company\/reclaim-finance-ong-think-tank"]},{"@type":"Person","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1","name":"L\u00e9o Martin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cebd89becb7f7185483789d7f51a21cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cebd89becb7f7185483789d7f51a21cb?s=96&d=mm&r=g","caption":"L\u00e9o Martin"},"url":"https:\/\/reclaimfinance.org\/site\/author\/lma\/"}]}},"_links":{"self":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts\/33626"}],"collection":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/comments?post=33626"}],"version-history":[{"count":0,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts\/33626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/media\/33631"}],"wp:attachment":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/media?parent=33626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/categories?post=33626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/tags?post=33626"},{"taxonomy":"acteurs_financiers","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/acteurs_financiers?post=33626"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/thematique?post=33626"},{"taxonomy":"webinar_type","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/webinar_type?post=33626"},{"taxonomy":"programme","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/programme?post=33626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}