{"id":36447,"date":"2025-04-29T01:01:25","date_gmt":"2025-04-28T23:01:25","guid":{"rendered":"https:\/\/reclaimfinance.org\/site\/?p=36447"},"modified":"2025-04-24T15:31:30","modified_gmt":"2025-04-24T13:31:30","slug":"banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires","status":"publish","type":"post","link":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/","title":{"rendered":"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-bottom:20px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-content-alignment:justify;--awb-text-color:var(--awb-color4);--awb-text-font-family:&quot;Montserrat&quot;;--awb-text-font-style:normal;--awb-text-font-weight:700;\"><p>Paris, le 29 avril 2025 &#8211; Aucune des 20 plus grandes banques europ\u00e9ennes n&rsquo;a de plan de transition cr\u00e9dible pour aligner ses activit\u00e9s sur une trajectoire 1,5\u00b0C. C\u2019est ce que r\u00e9v\u00e8le la nouvelle analyse de Reclaim Finance (1) qui a \u00e9valu\u00e9 les progr\u00e8s des banques sur 5 crit\u00e8res, dont leur strat\u00e9gie de d\u00e9carbonation, leur approche de l\u2019engagement et leur gouvernance (2). Quasiment toutes les banques ont obtenu une note inf\u00e9rieure \u00e0 50\/100, avec une moyenne de seulement 41\/100 &#8211; et parmi les banques fran\u00e7aises, le groupe Banque Populaire Caisse d\u2019Epargne se classe dernier avec seulement 31\/100. Devant ces r\u00e9sultats, qui prouvent la n\u00e9cessit\u00e9 d&rsquo;une r\u00e9glementation claire, Reclaim Finance appelle le Parlement europ\u00e9en et les \u00c9tats membres \u00e0 s&rsquo;assurer que les exigences existantes pour les plans de transition ne soient pas supprim\u00e9es par la r\u00e9cente proposition de d\u00e9r\u00e8glementation de la Commission europ\u00e9enne (Omnibus).<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-content-alignment:justify;\"><p>En s\u2019appuyant sur les informations non financi\u00e8res des 20 plus grandes banques europ\u00e9ennes (3), y compris les rapports CSRD publi\u00e9s pour la premi\u00e8re fois cette ann\u00e9e (4), l\u2019analyse montre que les banques europ\u00e9ennes aggravent la crise climatique par leur soutien continu aux activit\u00e9s les plus \u00e9mettrices de gaz \u00e0 effet de serre et celles responsables de l\u2019\u00e9rosion de la biodiversit\u00e9, comme le d\u00e9veloppement des \u00e9nergies fossiles (5). \u00c9valu\u00e9es sur leur strat\u00e9gie et leurs cibles de d\u00e9carbonation, leur strat\u00e9gie d&rsquo;engagement, leur reporting et gouvernance, ainsi que leur approche des th\u00e9matiques de transition juste et biodiversit\u00e9, les 20 banques obtiennent un score global moyen de seulement 41\/100.<\/p>\n<p>Plus inqui\u00e9tant encore, les banques obtiennent les scores les plus bas dans les cat\u00e9gories qui incluent des actions concr\u00e8tes pour r\u00e9duire leur impact n\u00e9gatif sur le climat et r\u00e9orienter leurs activit\u00e9s de financement (strat\u00e9gie de d\u00e9carbonation et strat\u00e9gie d&rsquo;engagement). Les notes les plus \u00e9lev\u00e9es concernent les crit\u00e8res de reporting et de gouvernance (moyenne 70\/100).<\/p>\n<p>Malgr\u00e9 leurs engagements (6), aucune des banques ne dispose d&rsquo;une strat\u00e9gie ad\u00e9quate pour atteindre la neutralit\u00e9 carbone d&rsquo;ici 2050, ce qui signifie que m\u00eame les banques les moins mal not\u00e9es doivent aller beaucoup plus loin pour montrer qu&rsquo;elles sont sur une voie cr\u00e9dible vers la transition.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_4_5 4_5 fusion-flex-column fusion-column-no-min-height centrer\" style=\"--awb-bg-size:cover;--awb-border-color:var(--awb-color4);--awb-border-style:solid;--awb-width-large:80%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.4%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.4%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><i class=\"fb-icon-element-1 fb-icon-element fontawesome-icon fa-quote-left fas circle-no fusion-text-flow\" style=\"--awb-font-size:23px;--awb-margin-bottom:10px;\"><\/i><div class=\"fusion-text fusion-text-3 fusion-text-no-margin\" style=\"--awb-content-alignment:justify;--awb-line-height:24px;--awb-text-transform:var(--awb-typography4-text-transform);--awb-text-color:var(--awb-color4);--awb-margin-bottom:10px;\"><p><em>Le secteur financier a un r\u00f4le essentiel \u00e0 jouer dans la r\u00e9alisation des ambitions de l&rsquo;Europe en mati\u00e8re de neutralit\u00e9 carbone, mais les plans de transition des banques europ\u00e9ennes sont loin de cet objectif. Notre analyse montre que les banques n&rsquo;adopteront pas de plans de transition cr\u00e9dibles \u00e0 moins d&rsquo;y \u00eatre oblig\u00e9es. Nous avons besoin de r\u00e8gles plus strictes pour garantir que les banques prennent la transition au s\u00e9rieux, alors pourquoi les dirigeants de l&rsquo;UE envisagent-ils de supprimer les obligations existantes en mati\u00e8re de planification de la transition ?<\/em><\/p>\n<\/div><div class=\"fusion-text fusion-text-4\"><p><strong>Christophe Etienne, analyste chez Reclaim Finance<\/strong><\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-5\" style=\"--awb-content-alignment:justify;\"><p>Si le rapport identifie quelques bonnes pratiques comme les politiques de la Banque Postale, seule banque \u00e0 mettre fin aux soutiens financiers au d\u00e9veloppement des \u00e9nergies fossiles, les cinq autres banques fran\u00e7aises passent sous la moyenne. Le groupe Banque Populaire Caisse d\u2019Epargne figure en queue de peloton des banques fran\u00e7aises, et \u00e0 la 18e place sur 20 au classement g\u00e9n\u00e9ral. BPCE se distingue ainsi par ses mauvaises pratiques, avec des soutiens persistants au charbon et une ignorance compl\u00e8te des enjeux de la biodiversit\u00e9 (score de 0 sur 100).<\/p>\n<p>De leur c\u00f4t\u00e9, BNP Paribas, Cr\u00e9dit Agricole, Soci\u00e9t\u00e9 G\u00e9n\u00e9rale et le Cr\u00e9dit Mutuel mettent l\u2019accent sur des cibles de d\u00e9carbonation encore lacunaires, sans suffisamment pr\u00e9senter leurs plans d\u2019action pour les atteindre.<\/p>\n<p>Alors que les banques europ\u00e9ennes sont tenues d&rsquo;adopter et de mettre en \u0153uvre des plans de transition dans le cadre des directives europ\u00e9ennes CSRD et CSDDD, les premiers devant \u00eatre pr\u00e9sent\u00e9s cette ann\u00e9e (7), l&rsquo;avenir de ces mesures est remis en question par la proposition Omnibus de la Commission europ\u00e9enne. Pourtant, l&rsquo;UE compte sur le financement priv\u00e9 pour soutenir la transition, avec 620 milliards d&rsquo;euros suppl\u00e9mentaires par an n\u00e9cessaires pour atteindre ses objectifs climatiques d\u2019apr\u00e8s cette m\u00eame Commission (8).<\/p>\n<p>Reclaim Finance appelle les membres du Parlement europ\u00e9en et les \u00c9tats membres \u00e0 reconna\u00eetre le r\u00f4le important des plans de transition et \u00e0 veiller \u00e0 ce que les obligations li\u00e9es \u00e0 leur adoption et leur mise en \u0153uvre soient maintenues dans la l\u00e9gislation existante en s\u2019opposant \u00e0 la loi Omnibus (9).<\/p>\n<\/div><div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-medium button-custom fusion-button-default button-1 fusion-button-default-span fusion-button-default-type\" style=\"--awb-margin-top:35px;--awb-margin-bottom:35px;--button_accent_color:#ffffff;--button_border_color:var(--awb-color4);--button_accent_hover_color:#ffffff;--button_border_hover_color:#8fc84c;--button_border_width-top:2px;--button_border_width-right:2px;--button_border_width-bottom:2px;--button_border_width-left:2px;--button_gradient_top_color:rgba(138,197,107,0);--button_gradient_bottom_color:rgba(138,197,107,0);--button_gradient_top_color_hover:#8fc84c;--button_gradient_bottom_color_hover:#8fc84c;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/plans-de-transition-des-banques-une-feuille-de-route-vers-nulle-part\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Lire le rapport<\/span><\/a><\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-column-no-min-height\" style=\"--awb-padding-top:20px;--awb-padding-right:10px;--awb-padding-bottom:20px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-size:cover;--awb-border-color:var(--awb-color4);--awb-border-top:2px;--awb-border-right:2px;--awb-border-bottom:2px;--awb-border-left:2px;--awb-border-style:solid;--awb-border-radius:10px 10px 10px 10px;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:0px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color4);--awb-margin-bottom:0px;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-font-size:18px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Montserrat&quot;;font-style:normal;font-weight:700;margin:0;font-size:1em;--fontSize:18;--minFontSize:18;line-height:1.5;\">Contacts :<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-6\"><ul>\n<li data-leveltext=\"\u25cf\" data-font=\"Roboto\" data-listid=\"2\" data-list-defn-props=\"\" aria-setsize=\"-1\" data-aria-posinset=\"1\" data-aria-level=\"1\"><span data-contrast=\"none\">Christophe Etienne, analyste chez Reclaim Finance, <\/span><a href=\"mailto:christophe@reclaimfinance.org\"><span data-contrast=\"none\">christophe@reclaimfinance.org<\/span><\/a><span data-contrast=\"none\">\u00a0<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\u25cf\" data-font=\"Roboto\" data-listid=\"2\" data-list-defn-props=\"\" aria-setsize=\"-1\" data-aria-posinset=\"2\" data-aria-level=\"1\"><span data-contrast=\"none\">Paul Schreiber, analyste chez Reclaim Finance, <\/span><a href=\"mailto:paul@reclaimfinance.org\"><span data-contrast=\"none\">paul@reclaimfinance.org<\/span><\/a><span data-contrast=\"none\">\u00a0<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<\/ul>\n<ul>\n<li data-leveltext=\"\u25cf\" data-font=\"Roboto\" data-listid=\"2\" data-list-defn-props=\"\" aria-setsize=\"-1\" data-aria-posinset=\"3\" data-aria-level=\"1\"><span data-contrast=\"none\">Sarah Bakaloglou, Charg\u00e9e des relations presse France, <\/span><a href=\"mailto:sarah@reclaimfinance.org\"><span data-contrast=\"none\">sarah@reclaimfinance.org<\/span><\/a><span data-contrast=\"none\">, +33661682510<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<\/ul>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-column-no-min-height\" style=\"--awb-padding-top:20px;--awb-padding-right:10px;--awb-padding-bottom:20px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-size:cover;--awb-border-color:var(--awb-color1);--awb-border-style:solid;--awb-border-radius:10px 10px 10px 10px;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-bottom:0px;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-font-size:18px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Montserrat&quot;;font-style:normal;font-weight:700;margin:0;font-size:1em;--fontSize:18;--minFontSize:18;line-height:1.5;\">Notes :<\/h2><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-7\" style=\"--awb-content-alignment:justify;\"><ol>\n<li><span data-contrast=\"none\">Reclaim Finance, <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/04\/Bank-transition-plans-a-roadmap-to-nowhere.pdf\" target=\"_blank\" rel=\"noopener\"><i>Bank Transition Plans \u2013 a roadmap to nowhere<\/i><\/a><\/span><span data-contrast=\"none\">, Reclaim Finance, Avril 2025<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"none\">L'analyse \u00e9tudie 60 crit\u00e8res regroup\u00e9s en <\/span><span data-contrast=\"none\">5 piliers th\u00e9matiques : les cibles de d\u00e9carbonation, la strat\u00e9gie de d\u00e9carbonation, la strat\u00e9gie d'engagement, le reporting et la gouvernance, et la transition juste et la biodiversit\u00e9.<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"none\">Les 20 banques europ\u00e9ennes analys\u00e9es sont : <\/span><span data-contrast=\"none\">Barclays, BBVA, BNP Paribas, BPCE Group, Cr\u00e9dit Agricole, Cr\u00e9dit Mutuel, Deutsche Bank, DZ Bank, HSBC, ING, Intesa Sanpaolo, La Banque Postale, Lloyds Banking <\/span><span data-contrast=\"none\">Group, NatWest, Rabobank, Santander, Soci\u00e9t\u00e9 G\u00e9n\u00e9rale, Standard Chartered, UBS, UniCredit.<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"none\">Les premi\u00e8res entreprises soumises \u00e0 la directive doivent publier leurs premiers rapports CSRD relatifs \u00e0 l'exercice 2024 en 2025. Toutes les banques europ\u00e9ennes et les filiales europ\u00e9ennes de banques non europ\u00e9ennes analys\u00e9es dans ce rapport font partie de ces entreprises et 14 d'entre elles doivent publier leur premier rapport CSRD cette ann\u00e9e. Au 1er avril 2025, 11 des banques analys\u00e9es avaient publi\u00e9 une d\u00e9claration de durabilit\u00e9 conforme \u00e0 la CSRD. Ces d\u00e9clarations ont \u00e9t\u00e9 examin\u00e9es et incluses dans cette analyse.<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"none\">Le rapport examine les objectifs de d\u00e9carbonation des banques pour neuf secteurs \u00e0 fortes \u00e9missions : l'agriculture, l'aluminium, le ciment, le charbon, l'immobilier commercial et r\u00e9sidentiel, le fer et l'acier, le p\u00e9trole et le gaz, la production d'\u00e9lectricit\u00e9 et les transports. En outre, \u00e0 travers son analyse des strat\u00e9gies de d\u00e9carbonation, le rapport couvre les politiques sectorielles mises en \u0153uvre par les banques en ce qui concerne les \u00e9nergies fossiles et les activit\u00e9s pr\u00e9sentant un risque \u00e9lev\u00e9 de d\u00e9forestation.<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"none\">Toutes les banques analys\u00e9es, \u00e0 l'exception de DZ Bank, sont membres de la Net Zero Banking Alliance (NZBA) et s'\u00e9taient engag\u00e9es \u00e0 s'aligner avec une trajectoire 1,5\u00b0c (jusqu'en avril 2025).<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"none\">La directive CSRD exige des entreprises concern\u00e9es par son champ d'application qu'elles rendent compte de leurs plans de transition sur le principe de \"se conformer ou expliquer\" (\"comply or explain\"), ce qui veut dire qu'elles peuvent ne pas le faire si elles le justifient. La directive CSDDD oblige les entreprises dans son p\u00e9rim\u00e8tre \u00e0 adopter des plans de transitions climat, et \u00e0 fournir des informations cr\u00e9dibles qui prouvent qu'elles les mettent en \u0153uvre.<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"none\">Voir <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/eur-lex.europa.eu\/legal-content\/EN\/TXT\/?uri=COM:2023:376:FIN\" target=\"_blank\" rel=\"noopener\">cette communication<\/a><\/span><span data-contrast=\"none\"> de l'Union europ\u00e9enne\u00a0<\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<li>R<span data-contrast=\"none\">eclaim Finance, <\/span><span style=\"text-decoration: underline;\"><a href=\"https:\/\/reclaimfinance.org\/site\/2025\/02\/26\/directive-omnibus-vers-un-affaiblissement-historique-des-normes-esg-en-europe\/\" target=\"_blank\" rel=\"noopener\">Directive Omnibus : vers un affaiblissement historique des normes ESG en Europe \u2013 Reclaim Finance<\/a><\/span><span data-ccp-props=\"\">\u00a0<\/span><\/li>\n<\/ol>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-bottom:0px;--awb-margin-top-small:0px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;text-transform:uppercase;--fontSize:33;line-height:1.5;\">Lire aussi<\/h2><\/div><div class=\"fusion-separator\" style=\"align-self: flex-start;margin-right:auto;margin-top:25px;margin-bottom:35px;width:100%;max-width:100px;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color4);border-color:var(--awb-color4);border-top-width:10px;\"><\/div><\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:15px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -15px !important; margin-right:-15px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-blog-rollover fusion-blog-layout-grid fusion-blog-layout-grid-3 isotope fusion-blog-equal-heights\" data-pages=\"107\" data-grid-col-space=\"30\" style=\"margin: -15px -15px 0;min-height:500px;\"><article id=\"blog-1-post-39896\" class=\"fusion-post-grid post-39896 post type-post status-publish format-standard has-post-thumbnail hentry category-communique-de-presse acteurs_financiers-banques-fr thematique-energies-fossiles programme-programme-1-fr\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/06\/LNG-tanker-ship-.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/06\/09\/energies-fossiles-des-signaux-encourageants-chez-les-banques-francaises-a-lexception-de-societe-generale\/\" aria-label=\"Energies fossiles : des signaux encourageants chez les banques fran\u00e7aises, \u00e0 l\u2019exception de Soci\u00e9t\u00e9 G\u00e9n\u00e9rale\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/06\/09\/energies-fossiles-des-signaux-encourageants-chez-les-banques-francaises-a-lexception-de-societe-generale\/\">Energies fossiles : des signaux encourageants chez les banques fran\u00e7aises, \u00e0 l\u2019exception de Soci\u00e9t\u00e9 G\u00e9n\u00e9rale<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/aman\/\" rel=\"author\">Aatira\u00ef Manickawasagar<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-06-09T09:26:44+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/communique-de-presse\/\" rel=\"category tag\">Communiqu\u00e9s de presse<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-39929\" class=\"fusion-post-grid post-39929 post type-post status-publish format-standard has-post-thumbnail hentry category-communique-de-presse acteurs_financiers-assurances-fr thematique-energies-fossiles thematique-gaz-fr programme-programme-1-fr\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/06\/Coral-1-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/06\/09\/triangle-de-corail-lexpansion-du-gnl-soutenue-par-les-assureurs-menace-lecosysteme-marin-le-plus-riche-au-monde\/\" aria-label=\"Triangle de Corail : l\u2019expansion du GNL soutenue par les assureurs menace l\u2019\u00e9cosyst\u00e8me marin le plus riche au monde\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/06\/09\/triangle-de-corail-lexpansion-du-gnl-soutenue-par-les-assureurs-menace-lecosysteme-marin-le-plus-riche-au-monde\/\">Triangle de Corail : l\u2019expansion du GNL soutenue par les assureurs menace l\u2019\u00e9cosyst\u00e8me marin le plus riche au monde<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/aman\/\" rel=\"author\">Aatira\u00ef Manickawasagar<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-06-08T16:03:12+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/communique-de-presse\/\" rel=\"category tag\">Communiqu\u00e9s de presse<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-39865\" class=\"fusion-post-grid post-39865 post type-post status-publish format-standard has-post-thumbnail hentry category-communique-de-presse thematique-energies-fossiles thematique-gaz-fr programme-programme-2-fr\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/05\/TotalEnergies-EPH.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/05\/20\/lalliance-entre-totalenergies-et-eph-risque-denfermer-leurope-dans-le-gaz-fossile\/\" aria-label=\"L&rsquo;alliance entre TotalEnergies et EPH risque d&rsquo;enfermer l&rsquo;Europe dans le gaz fossile\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/05\/20\/lalliance-entre-totalenergies-et-eph-risque-denfermer-leurope-dans-le-gaz-fossile\/\">L&rsquo;alliance entre TotalEnergies et EPH risque d&rsquo;enfermer l&rsquo;Europe dans le gaz fossile<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/lma\/\" rel=\"author\">L\u00e9o Martin<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-05-19T11:51:33+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/communique-de-presse\/\" rel=\"category tag\">Communiqu\u00e9s de presse<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":26,"featured_media":36448,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[36],"tags":[],"acteurs_financiers":[2276],"thematique":[2415],"webinar_type":[],"programme":[],"class_list":["post-36447","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communique-de-presse","acteurs_financiers-banques-fr","thematique-energies-fossiles"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires - Reclaim Finance<\/title>\n<meta name=\"description\" content=\"Aucune des 20 plus grandes banques europ\u00e9ennes n&#039;a de plan de transition cr\u00e9dible pour aligner ses activit\u00e9s sur une trajectoire 1,5\u00b0C.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires - Reclaim Finance\" \/>\n<meta property=\"og:description\" content=\"Aucune des 20 plus grandes banques europ\u00e9ennes n&#039;a de plan de transition cr\u00e9dible pour aligner ses activit\u00e9s sur une trajectoire 1,5\u00b0C.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/\" \/>\n<meta property=\"og:site_name\" content=\"Reclaim Finance\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ReclaimFinanceONG\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-28T23:01:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/04\/Bank-energy-transition.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1013\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ReclaimFinance\" \/>\n<meta name=\"twitter:site\" content=\"@ReclaimFinance\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00e9o Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/\"},\"author\":{\"name\":\"L\u00e9o Martin\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#\\\/schema\\\/person\\\/92f0f8d102e5e411f092871d8eeb3db1\"},\"headline\":\"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires\",\"datePublished\":\"2025-04-28T23:01:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/\"},\"wordCount\":4213,\"publisher\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Bank-energy-transition.png\",\"articleSection\":[\"Communiqu\u00e9s de presse\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/\",\"url\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/\",\"name\":\"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires - Reclaim Finance\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Bank-energy-transition.png\",\"datePublished\":\"2025-04-28T23:01:25+00:00\",\"description\":\"Aucune des 20 plus grandes banques europ\u00e9ennes n'a de plan de transition cr\u00e9dible pour aligner ses activit\u00e9s sur une trajectoire 1,5\u00b0C.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/#primaryimage\",\"url\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Bank-energy-transition.png\",\"contentUrl\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/wp-content\\\/uploads\\\/2025\\\/04\\\/Bank-energy-transition.png\",\"width\":1013,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/2025\\\/04\\\/29\\\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#website\",\"url\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/\",\"name\":\"Reclaim Finance\",\"description\":\"Reprendre le contr\u00f4le de la finance pour le climat et la biodiversit\u00e9\",\"publisher\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#organization\",\"name\":\"Reclaim Finance\",\"url\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_RC_space.png\",\"contentUrl\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/wp-content\\\/uploads\\\/2020\\\/03\\\/logo_RC_space.png\",\"width\":800,\"height\":800,\"caption\":\"Reclaim Finance\"},\"image\":{\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ReclaimFinanceONG\",\"https:\\\/\\\/x.com\\\/ReclaimFinance\",\"https:\\\/\\\/www.instagram.com\\\/reclaimfinance\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/reclaim-finance-ong-think-tank\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/#\\\/schema\\\/person\\\/92f0f8d102e5e411f092871d8eeb3db1\",\"name\":\"L\u00e9o Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/102aa59a905e756d0b83dcf028da5f849372c02f07ba09d153941845a348e607?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/102aa59a905e756d0b83dcf028da5f849372c02f07ba09d153941845a348e607?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/102aa59a905e756d0b83dcf028da5f849372c02f07ba09d153941845a348e607?s=96&d=mm&r=g\",\"caption\":\"L\u00e9o Martin\"},\"url\":\"https:\\\/\\\/reclaimfinance.org\\\/site\\\/author\\\/lma\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires - Reclaim Finance","description":"Aucune des 20 plus grandes banques europ\u00e9ennes n'a de plan de transition cr\u00e9dible pour aligner ses activit\u00e9s sur une trajectoire 1,5\u00b0C.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/","og_locale":"fr_FR","og_type":"article","og_title":"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires - Reclaim Finance","og_description":"Aucune des 20 plus grandes banques europ\u00e9ennes n'a de plan de transition cr\u00e9dible pour aligner ses activit\u00e9s sur une trajectoire 1,5\u00b0C.","og_url":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/","og_site_name":"Reclaim Finance","article_publisher":"https:\/\/www.facebook.com\/ReclaimFinanceONG","article_published_time":"2025-04-28T23:01:25+00:00","og_image":[{"width":1013,"height":450,"url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/04\/Bank-energy-transition.png","type":"image\/png"}],"author":"L\u00e9o Martin","twitter_card":"summary_large_image","twitter_creator":"@ReclaimFinance","twitter_site":"@ReclaimFinance","twitter_misc":{"\u00c9crit par":"L\u00e9o Martin","Dur\u00e9e de lecture estim\u00e9e":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/#article","isPartOf":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/"},"author":{"name":"L\u00e9o Martin","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1"},"headline":"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires","datePublished":"2025-04-28T23:01:25+00:00","mainEntityOfPage":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/"},"wordCount":4213,"publisher":{"@id":"https:\/\/reclaimfinance.org\/site\/#organization"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/#primaryimage"},"thumbnailUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/04\/Bank-energy-transition.png","articleSection":["Communiqu\u00e9s de presse"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/","url":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/","name":"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires - Reclaim Finance","isPartOf":{"@id":"https:\/\/reclaimfinance.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/#primaryimage"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/#primaryimage"},"thumbnailUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/04\/Bank-energy-transition.png","datePublished":"2025-04-28T23:01:25+00:00","description":"Aucune des 20 plus grandes banques europ\u00e9ennes n'a de plan de transition cr\u00e9dible pour aligner ses activit\u00e9s sur une trajectoire 1,5\u00b0C.","breadcrumb":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/#primaryimage","url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/04\/Bank-energy-transition.png","contentUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/04\/Bank-energy-transition.png","width":1013,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/reclaimfinance.org\/site\/2025\/04\/29\/banques-europeennes-une-reglementation-necessaire-face-a-des-plans-de-transition-lacunaires\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reclaimfinance.org\/site\/"},{"@type":"ListItem","position":2,"name":"Banques europ\u00e9ennes : une r\u00e9glementation n\u00e9cessaire face \u00e0 des plans de transition lacunaires"}]},{"@type":"WebSite","@id":"https:\/\/reclaimfinance.org\/site\/#website","url":"https:\/\/reclaimfinance.org\/site\/","name":"Reclaim Finance","description":"Reprendre le contr\u00f4le de la finance pour le climat et la biodiversit\u00e9","publisher":{"@id":"https:\/\/reclaimfinance.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reclaimfinance.org\/site\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/reclaimfinance.org\/site\/#organization","name":"Reclaim Finance","url":"https:\/\/reclaimfinance.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png","contentUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png","width":800,"height":800,"caption":"Reclaim Finance"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ReclaimFinanceONG","https:\/\/x.com\/ReclaimFinance","https:\/\/www.instagram.com\/reclaimfinance\/","https:\/\/www.linkedin.com\/company\/reclaim-finance-ong-think-tank"]},{"@type":"Person","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1","name":"L\u00e9o Martin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/102aa59a905e756d0b83dcf028da5f849372c02f07ba09d153941845a348e607?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/102aa59a905e756d0b83dcf028da5f849372c02f07ba09d153941845a348e607?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/102aa59a905e756d0b83dcf028da5f849372c02f07ba09d153941845a348e607?s=96&d=mm&r=g","caption":"L\u00e9o Martin"},"url":"https:\/\/reclaimfinance.org\/site\/author\/lma\/"}]}},"_links":{"self":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts\/36447","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/comments?post=36447"}],"version-history":[{"count":2,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts\/36447\/revisions"}],"predecessor-version":[{"id":36450,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts\/36447\/revisions\/36450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/media\/36448"}],"wp:attachment":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/media?parent=36447"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/categories?post=36447"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/tags?post=36447"},{"taxonomy":"acteurs_financiers","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/acteurs_financiers?post=36447"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/thematique?post=36447"},{"taxonomy":"webinar_type","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/webinar_type?post=36447"},{"taxonomy":"programme","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/programme?post=36447"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}