{"id":38517,"date":"2025-12-01T00:01:56","date_gmt":"2025-11-30T23:01:56","guid":{"rendered":"https:\/\/reclaimfinance.org\/site\/?p=38517"},"modified":"2025-12-31T12:30:06","modified_gmt":"2025-12-31T11:30:06","slug":"pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles","status":"publish","type":"post","link":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/","title":{"rendered":"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles"},"content":{"rendered":"<p><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-bottom:20px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-text fusion-text-1\" style=\"--awb-content-alignment:justify;--awb-text-color:var(--awb-color4);--awb-text-font-family:&quot;Montserrat&quot;;--awb-text-font-style:normal;--awb-text-font-weight:700;\"><p>Dans une lettre ouverte intitul\u00e9e \u00ab\u202f<em>Les jeunes g\u00e9n\u00e9rations se pr\u00e9occupent de leurs retraites en demandant le retrait des \u00e9nergies fossiles\u202f<\/em>\u00bb, Reclaim Finance et 19 organisations de jeunes et d\u2019\u00e9tudiants appellent les acteurs des retraites \u00e0 cesser de soutenir le d\u00e9veloppement des \u00e9nergies fossiles. La lettre s\u2019adresse sp\u00e9cifiquement \u00e0 trois institutions\u202f: l\u2019Agirc-Arrco (le r\u00e9gime de retraite compl\u00e9mentaire des salari\u00e9s du secteur priv\u00e9), l\u2019ERAFP (celui des fonctionnaires), et le Fonds de r\u00e9serve pour les retraites. Les signataires rappellent les soutiens persistants de ces acteurs \u00e0 l\u2019expansion fossile, que Reclaim Finance r\u00e9v\u00e9lait dans un <span style=\"text-decoration: underline;\"><a style=\"color: #8ac56b;\" href=\"https:\/\/reclaimfinance.org\/site\/2025\/07\/08\/retraites-et-climat-des-acteurs-cles-investissent-dans-les-energies-fossiles\/\" target=\"_blank\" rel=\"noopener\">rapport r\u00e9cent<\/a><\/span>, et demandent la mise en \u0153uvre de mesures concr\u00e8tes pour prot\u00e9ger les jeunes g\u00e9n\u00e9rations des cons\u00e9quences du changement climatique, en prenant en compte les pr\u00e9conisations scientifiques.<\/p>\n<\/div><div class=\"fusion-text fusion-text-2\" style=\"--awb-content-alignment:justify;\"><p>Madame, Monsieur,<\/p>\n<p>Jeunes citoyens, actifs ou en formation, nous sommes pr\u00e9occup\u00e9s par les cons\u00e9quences du changement climatique sur l\u2019avenir des g\u00e9n\u00e9rations actuelles et futures. En tant que gestionnaires des retraites en France, nous souhaitons vous rappeler aujourd\u2019hui votre responsabilit\u00e9 dans la pr\u00e9servation et la s\u00e9curisation de notre avenir collectif.<\/p>\n<p>Notre g\u00e9n\u00e9ration, ainsi que les futures, sont celles qui subiront le plus les d\u00e9g\u00e2ts du changement climatique. Multiplication des vagues de chaleur et des s\u00e9cheresses, accroissement de la tension sur les ressources en eau, intensification des inondations, \u00e9l\u00e9vation du niveau de la mer, perte de biodiversit\u00e9, baisse significative des rendements agricoles\u202f: les impacts du r\u00e9chauffement sont d\u00e9j\u00e0 l\u00e0 et ne feront que s\u2019intensifier dans les prochaines d\u00e9cennies en l\u2019absence d\u2019une transformation en profondeur de notre syst\u00e8me \u00e9conomique et productif.<\/p>\n<p>Les scientifiques du GIEC sont clairs\u202f: l&rsquo;une des principales sources de gaz \u00e0 effet de serre est la\u202fcombustion d&rsquo;\u00e9nergies fossiles, et tout nouveau projet d\u2019\u00e9nergies fossiles nous \u00e9loigne de l\u2019objectif de limiter le r\u00e9chauffement plan\u00e9taire \u00e0 1,5\u00b0C.<\/p>\n<p>Pourtant, les grandes entreprises du secteur du charbon, du p\u00e9trole et du gaz continuent de d\u00e9velopper de nouveaux projets, nous enfermant dans une d\u00e9pendance aux \u00e9nergies fossiles. Certaines n&rsquo;h\u00e9sitent pas \u00e0 reculer sur leurs maigres engagements climatiques. C&rsquo;est notamment le cas de TotalEnergies qui a revu \u00e0 la hausse ses objectifs de production de p\u00e9trole et de gaz d\u2019ici 2030 et a diminu\u00e9 la part du bas carbone dans ses investissements, et de BP qui a abandonn\u00e9 une grande partie de ses objectifs climatiques pour privil\u00e9gier le p\u00e9trole et le gaz.<\/p>\n<p>Malgr\u00e9 cela, des acteurs financiers publics et priv\u00e9s &#8211; dont vous faites partie &#8211; continuent de soutenir financi\u00e8rement l&rsquo;industrie toxique des \u00e9nergies fossiles.<\/p>\n<p>Si vous avez d\u00e9j\u00e0 adopt\u00e9 quelques mesures pour cesser de soutenir certaines entreprises n\u00e9fastes pour le climat, celles-ci ne sont pas suffisantes : votre organisation peut demain fournir de l\u2019argent \u00e0 des acteurs en premi\u00e8re ligne de l\u2019expansion fossile comme TotalEnergies, notamment via vos investissements dans leurs obligations. Cela vous rend complices de leurs strat\u00e9gies \u00e0 contresens de la science.<\/p>\n<p>Vos investissements sont par ailleurs confi\u00e9s en partie \u00e0 des soci\u00e9t\u00e9s de gestion qui s\u2019affichent comme des alli\u00e9s ind\u00e9fectibles de l\u2019industrie fossile, comme BlackRock, cautionnant ainsi leurs pratiques n\u00e9fastes pour le climat.<\/p>\n<p>Au moment des assembl\u00e9es g\u00e9n\u00e9rales, nous ne vous voyons pas vous opposer publiquement aux strat\u00e9gies climaticides port\u00e9es par les conseils d\u2019administration des entreprises fossiles, alors que vous disposez d\u2019un pouvoir d\u2019influence important en tant qu\u2019actionnaires, surtout avec vos votes.<\/p>\n<p>Comment peut-on se pr\u00e9senter comme un investisseur responsable, garant des retraites des g\u00e9n\u00e9rations actuelles et futures, et agir contre l\u2019int\u00e9r\u00eat de celles-ci en soutenant des entreprises climaticides ?<\/p>\n<p>Derri\u00e8re vos soutiens \u00e0 l\u2019expansion fossile, ce sont nos vies qui sont menac\u00e9es &#8211; notre sant\u00e9, notre s\u00e9curit\u00e9 alimentaire, notre stabilit\u00e9 \u00e9conomique et nos d\u00e9mocraties.<\/p>\n<p>Il y a urgence \u00e0 prendre r\u00e9ellement conscience des dangers que repr\u00e9sente le changement climatique, et utiliser d\u00e8s maintenant tous les moyens dont vous disposez pour lutter contre.<\/p>\n<p>Nous vous demandons de mettre en \u0153uvre rapidement des mesures concr\u00e8tes, ambitieuses et publiques pour\u202fmettre un terme \u00e0 tout nouveau soutien aux entreprises qui d\u00e9veloppent de nouveaux projets de charbon, p\u00e9trole et gaz.<\/p>\n<p>Nous croyons fermement que ces mesures ne sont pas seulement une exigence morale, mais aussi une condition de viabilit\u00e9 pour vos institutions, pour les retraites futures, et pour les jeunes et futures g\u00e9n\u00e9rations.<\/p>\n<p>Nous vous remercions par avance de l\u2019attention que vous porterez \u00e0 cette lettre, et restons \u00e0 votre disposition pour discuter de la construction d\u2019un syst\u00e8me de retraite respectueux des g\u00e9n\u00e9rations \u00e0 venir.<\/p>\n<\/div><\/div><\/div><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column fusion-column-no-min-height\" style=\"--awb-padding-top:20px;--awb-padding-right:10px;--awb-padding-bottom:20px;--awb-padding-left:10px;--awb-overflow:hidden;--awb-bg-size:cover;--awb-border-color:var(--awb-color1);--awb-border-top:1px;--awb-border-right:1px;--awb-border-bottom:1px;--awb-border-left:1px;--awb-border-style:solid;--awb-border-radius:10px 10px 10px 10px;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-1 fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-bottom:0px;--awb-font-size:16px;\"><div class=\"title-sep-container title-sep-container-left fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><span class=\"awb-title-spacer fusion-no-large-visibility fusion-no-medium-visibility fusion-no-small-visibility\"><\/span><h3 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Montserrat&quot;;font-style:normal;font-weight:700;margin:0;font-size:1em;--fontSize:16;--minFontSize:16;line-height:1.5;\">Signataires :<\/h3><span class=\"awb-title-spacer\"><\/span><div class=\"title-sep-container title-sep-container-right\"><div class=\"title-sep sep- sep-solid\" style=\"border-color:#3e3e3e;\"><\/div><\/div><\/div><div class=\"fusion-text fusion-text-3\"><ul>\n<li><span data-contrast=\"auto\">Assas Environnement<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Avenir Climatique<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">CERCLE &#8211; Construisons Ensemble une R\u00e9flexion CoLLective \u00c9tudiante (AgroParisTech)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Collectif Pour un R\u00e9veil Ecologique<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">D\u00e9clic Collectif<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">EIES (Entreprises Illegitimes dans l&rsquo;Enseignement Superieur)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Esp\u2019R (HEC Paris)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">FAGE (F\u00e9d\u00e9ration des Associations G\u00e9n\u00e9rales Etudiantes)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Fridays for Future France<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">GALILL\u00c9 (Groupement des Associations Lilloises \u00c9tudiantes)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Impact CentraleSup\u00e9lec<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">NeXt (\u00c9cole polytechnique)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">NOISE emlyon<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">NOISE ESCP<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">PC Durable (ESPCI)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Re.boot<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">RESES (R\u00e9seau \u00c9tudiant pour une Soci\u00e9t\u00e9 \u00c9cologique et Solidaire)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Sciences Po Environnement Paris<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Terre \u00e0 Terre (ENS Paris Saclay)<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<li><span data-contrast=\"auto\">Reclaim Finance<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335559739&quot;:0,&quot;335559740&quot;:240}\">\u00a0<\/span><\/li>\n<\/ul>\n<\/div><\/div><\/div><\/div><\/div><div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container has-pattern-background has-mask-background nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-flex-wrap:wrap;\" ><div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"max-width:1216.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\"><div class=\"fusion-title title fusion-title-2 fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:var(--awb-color1);--awb-margin-bottom:0px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"margin:0;text-transform:uppercase;--fontSize:33;line-height:1.5;\">lire aussi<\/h2><\/div><div class=\"fusion-separator\" style=\"align-self: flex-start;margin-right:auto;margin-top:25px;margin-bottom:35px;width:100%;max-width:100px;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:var(--awb-color4);border-color:var(--awb-color4);border-top-width:10px;\"><\/div><\/div><div class=\"fusion-blog-shortcode fusion-blog-shortcode-1 fusion-blog-archive fusion-blog-layout-grid-wrapper fusion-blog-no\"><style type=\"text\/css\">.fusion-blog-shortcode-1 .fusion-blog-layout-grid .fusion-post-grid{padding:15px;}.fusion-blog-shortcode-1 .fusion-posts-container{margin-left: -15px !important; margin-right:-15px !important;}<\/style><div class=\"fusion-posts-container fusion-posts-container-no fusion-blog-rollover fusion-blog-layout-grid fusion-blog-layout-grid-3 isotope fusion-blog-equal-heights\" data-pages=\"183\" data-grid-col-space=\"30\" style=\"margin: -15px -15px 0;min-height:500px;\"><article id=\"blog-1-post-40051\" class=\"fusion-post-grid post-40051 post type-post status-publish format-standard has-post-thumbnail hentry category-blog acteurs_financiers-banques-fr thematique-energies-fossiles thematique-gaz-fr programme-programme-2-fr\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/07\/Nordea1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"Gas expansion\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/07\/06\/les-banques-francaises-au-soutien-deph-a-rebours-de-leurs-engagements\/\" aria-label=\"Les banques fran\u00e7aises au soutien d\u2019EPH, \u00e0 rebours de leurs engagements\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/07\/06\/les-banques-francaises-au-soutien-deph-a-rebours-de-leurs-engagements\/\">Les banques fran\u00e7aises au soutien d\u2019EPH, \u00e0 rebours de leurs engagements<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/lma\/\" title=\"Articles par L\u00e9o Martin\" rel=\"author\">L\u00e9o Martin<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-06T15:58:19+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/blog\/\" rel=\"category tag\">Articles<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-40057\" class=\"fusion-post-grid post-40057 post type-post status-publish format-standard has-post-thumbnail hentry category-blog thematique-energies-fossiles thematique-petrole-et-gaz programme-programme-1-fr\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/07\/Nordea.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/07\/06\/nordea-se-demarque-du-soutien-des-banques-europeennes-a-lexpansion-du-gnl\/\" aria-label=\"Nordea se d\u00e9marque du soutien des banques europ\u00e9ennes \u00e0 l&rsquo;expansion du GNL\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/07\/06\/nordea-se-demarque-du-soutien-des-banques-europeennes-a-lexpansion-du-gnl\/\">Nordea se d\u00e9marque du soutien des banques europ\u00e9ennes \u00e0 l&rsquo;expansion du GNL<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/lma\/\" title=\"Articles par L\u00e9o Martin\" rel=\"author\">L\u00e9o Martin<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-06T16:05:25+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/blog\/\" rel=\"category tag\">Articles<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<article id=\"blog-1-post-40027\" class=\"fusion-post-grid post-40027 post type-post status-publish format-standard has-post-thumbnail hentry category-blog thematique-energies-fossiles\">\n<div class=\"fusion-post-wrapper\" style=\"background-color:rgba(255,255,255,0);border:1px solid #2a2b3d;border-bottom-width:3px;\">\n\n\t\t\t<div class=\"fusion-flexslider flexslider fusion-flexslider-loading fusion-post-slideshow\" style=\"border-color:#2a2b3d;\">\n\t\t<ul class=\"slides\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<li><div  class=\"fusion-image-wrapper\" aria-haspopup=\"true\">\n\t\t\t\t<img decoding=\"async\" width=\"1125\" height=\"500\" src=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2026\/06\/fossil-fuel-1-1.png\" class=\"attachment-full size-full wp-post-image\" alt=\"\" \/><div class=\"fusion-rollover\">\n\t<div class=\"fusion-rollover-content\">\n\n\t\t\t\t\n\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\n\t\t\t\t\t\t<a class=\"fusion-link-wrapper\" href=\"https:\/\/reclaimfinance.org\/site\/2026\/06\/26\/politiques-fossiles-que-dit-la-recherche-academique\/\" aria-label=\"Politiques fossiles : que dit la recherche acad\u00e9mique\"><\/a>\n\t<\/div>\n<\/div>\n<\/div>\n<\/li>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t<\/ul>\n\t<\/div>\n\t<div class=\"fusion-post-content-wrapper\" style=\"padding:30px 25px 20px 25px;\"><div class=\"fusion-post-content post-content\"><h3 class=\"blog-shortcode-post-title entry-title\"><a href=\"https:\/\/reclaimfinance.org\/site\/2026\/06\/26\/politiques-fossiles-que-dit-la-recherche-academique\/\">Politiques fossiles : que dit la recherche acad\u00e9mique<\/a><\/h3><p class=\"fusion-single-line-meta\"><span class=\"vcard\" style=\"display: none;\"><span class=\"fn\"><a href=\"https:\/\/reclaimfinance.org\/site\/author\/aman\/\" title=\"Articles par Aatira\u00ef Manickawasagar\" rel=\"author\">Aatira\u00ef Manickawasagar<\/a><\/span><\/span><span class=\"updated\" style=\"display:none;\">2026-07-10T11:28:08+02:00<\/span><a href=\"https:\/\/reclaimfinance.org\/site\/category\/blog\/\" rel=\"category tag\">Articles<\/a><span class=\"fusion-inline-sep\">|<\/span><\/p><\/div><\/div><div class=\"fusion-clearfix\"><\/div><\/div>\n<\/article>\n<div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":26,"featured_media":38519,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[45],"tags":[],"acteurs_financiers":[2432],"thematique":[2415],"webinar_type":[],"programme":[3731],"class_list":["post-38517","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","acteurs_financiers-gestionnaire-dactifs","thematique-energies-fossiles","programme-programme-3-fr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles - Reclaim Finance<\/title>\n<meta name=\"description\" content=\"Reclaim Finance et 19 organisations de jeunes et d\u2019\u00e9tudiants appellent les acteurs des retraites \u00e0 cesser de soutenir le d\u00e9veloppement des \u00e9nergies fossiles.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles - Reclaim Finance\" \/>\n<meta property=\"og:description\" content=\"Reclaim Finance et 19 organisations de jeunes et d\u2019\u00e9tudiants appellent les acteurs des retraites \u00e0 cesser de soutenir le d\u00e9veloppement des \u00e9nergies fossiles.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/\" \/>\n<meta property=\"og:site_name\" content=\"Reclaim Finance\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ReclaimFinanceONG\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-30T23:01:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-31T11:30:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1013\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"L\u00e9o Martin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ReclaimFinance\" \/>\n<meta name=\"twitter:site\" content=\"@ReclaimFinance\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"L\u00e9o Martin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/\"},\"author\":{\"name\":\"L\u00e9o Martin\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1\"},\"headline\":\"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles\",\"datePublished\":\"2025-11-30T23:01:56+00:00\",\"dateModified\":\"2025-12-31T11:30:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/\"},\"wordCount\":2667,\"publisher\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/#organization\"},\"image\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png\",\"articleSection\":[\"Articles\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/\",\"url\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/\",\"name\":\"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles - Reclaim Finance\",\"isPartOf\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png\",\"datePublished\":\"2025-11-30T23:01:56+00:00\",\"dateModified\":\"2025-12-31T11:30:06+00:00\",\"description\":\"Reclaim Finance et 19 organisations de jeunes et d\u2019\u00e9tudiants appellent les acteurs des retraites \u00e0 cesser de soutenir le d\u00e9veloppement des \u00e9nergies fossiles.\",\"breadcrumb\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#primaryimage\",\"url\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png\",\"contentUrl\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png\",\"width\":1013,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/reclaimfinance.org\/site\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#website\",\"url\":\"https:\/\/reclaimfinance.org\/site\/\",\"name\":\"Reclaim Finance\",\"description\":\"Reprendre le contr\u00f4le de la finance pour le climat et la biodiversit\u00e9\",\"publisher\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/reclaimfinance.org\/site\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#organization\",\"name\":\"Reclaim Finance\",\"url\":\"https:\/\/reclaimfinance.org\/site\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png\",\"contentUrl\":\"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png\",\"width\":800,\"height\":800,\"caption\":\"Reclaim Finance\"},\"image\":{\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/ReclaimFinanceONG\",\"https:\/\/x.com\/ReclaimFinance\",\"https:\/\/www.instagram.com\/reclaimfinance\/\",\"https:\/\/www.linkedin.com\/company\/reclaim-finance-ong-think-tank\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1\",\"name\":\"L\u00e9o Martin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/cebd89becb7f7185483789d7f51a21cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/cebd89becb7f7185483789d7f51a21cb?s=96&d=mm&r=g\",\"caption\":\"L\u00e9o Martin\"},\"url\":\"https:\/\/reclaimfinance.org\/site\/author\/lma\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles - Reclaim Finance","description":"Reclaim Finance et 19 organisations de jeunes et d\u2019\u00e9tudiants appellent les acteurs des retraites \u00e0 cesser de soutenir le d\u00e9veloppement des \u00e9nergies fossiles.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/","og_locale":"fr_FR","og_type":"article","og_title":"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles - Reclaim Finance","og_description":"Reclaim Finance et 19 organisations de jeunes et d\u2019\u00e9tudiants appellent les acteurs des retraites \u00e0 cesser de soutenir le d\u00e9veloppement des \u00e9nergies fossiles.","og_url":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/","og_site_name":"Reclaim Finance","article_publisher":"https:\/\/www.facebook.com\/ReclaimFinanceONG","article_published_time":"2025-11-30T23:01:56+00:00","article_modified_time":"2025-12-31T11:30:06+00:00","og_image":[{"width":1013,"height":450,"url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png","type":"image\/png"}],"author":"L\u00e9o Martin","twitter_card":"summary_large_image","twitter_creator":"@ReclaimFinance","twitter_site":"@ReclaimFinance","twitter_misc":{"\u00c9crit par":"L\u00e9o Martin","Dur\u00e9e de lecture estim\u00e9e":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#article","isPartOf":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/"},"author":{"name":"L\u00e9o Martin","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1"},"headline":"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles","datePublished":"2025-11-30T23:01:56+00:00","dateModified":"2025-12-31T11:30:06+00:00","mainEntityOfPage":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/"},"wordCount":2667,"publisher":{"@id":"https:\/\/reclaimfinance.org\/site\/#organization"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#primaryimage"},"thumbnailUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png","articleSection":["Articles"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/","url":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/","name":"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles - Reclaim Finance","isPartOf":{"@id":"https:\/\/reclaimfinance.org\/site\/#website"},"primaryImageOfPage":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#primaryimage"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#primaryimage"},"thumbnailUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png","datePublished":"2025-11-30T23:01:56+00:00","dateModified":"2025-12-31T11:30:06+00:00","description":"Reclaim Finance et 19 organisations de jeunes et d\u2019\u00e9tudiants appellent les acteurs des retraites \u00e0 cesser de soutenir le d\u00e9veloppement des \u00e9nergies fossiles.","breadcrumb":{"@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#primaryimage","url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png","contentUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2025\/11\/Retraite-climat.png","width":1013,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/reclaimfinance.org\/site\/2025\/12\/01\/pour-leur-futur-les-jeunes-exigent-des-retraites-sans-energies-fossiles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/reclaimfinance.org\/site\/"},{"@type":"ListItem","position":2,"name":"Pour leur futur, les jeunes exigent des retraites sans \u00e9nergies fossiles"}]},{"@type":"WebSite","@id":"https:\/\/reclaimfinance.org\/site\/#website","url":"https:\/\/reclaimfinance.org\/site\/","name":"Reclaim Finance","description":"Reprendre le contr\u00f4le de la finance pour le climat et la biodiversit\u00e9","publisher":{"@id":"https:\/\/reclaimfinance.org\/site\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/reclaimfinance.org\/site\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/reclaimfinance.org\/site\/#organization","name":"Reclaim Finance","url":"https:\/\/reclaimfinance.org\/site\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/","url":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png","contentUrl":"https:\/\/reclaimfinance.org\/site\/wp-content\/uploads\/2020\/03\/logo_RC_space.png","width":800,"height":800,"caption":"Reclaim Finance"},"image":{"@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ReclaimFinanceONG","https:\/\/x.com\/ReclaimFinance","https:\/\/www.instagram.com\/reclaimfinance\/","https:\/\/www.linkedin.com\/company\/reclaim-finance-ong-think-tank"]},{"@type":"Person","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/92f0f8d102e5e411f092871d8eeb3db1","name":"L\u00e9o Martin","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/reclaimfinance.org\/site\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/cebd89becb7f7185483789d7f51a21cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/cebd89becb7f7185483789d7f51a21cb?s=96&d=mm&r=g","caption":"L\u00e9o Martin"},"url":"https:\/\/reclaimfinance.org\/site\/author\/lma\/"}]}},"_links":{"self":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts\/38517"}],"collection":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/comments?post=38517"}],"version-history":[{"count":2,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts\/38517\/revisions"}],"predecessor-version":[{"id":38520,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/posts\/38517\/revisions\/38520"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/media\/38519"}],"wp:attachment":[{"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/media?parent=38517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/categories?post=38517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/tags?post=38517"},{"taxonomy":"acteurs_financiers","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/acteurs_financiers?post=38517"},{"taxonomy":"thematique","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/thematique?post=38517"},{"taxonomy":"webinar_type","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/webinar_type?post=38517"},{"taxonomy":"programme","embeddable":true,"href":"https:\/\/reclaimfinance.org\/site\/wp-json\/wp\/v2\/programme?post=38517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}